{"id":1003,"date":"2024-11-05T12:00:00","date_gmt":"2024-11-05T11:00:00","guid":{"rendered":"https:\/\/simon.blog\/?post_type=talk&#038;p=1003"},"modified":"2026-06-10T11:17:38","modified_gmt":"2026-06-10T09:17:38","slug":"greener-better-faster-stronger","status":"publish","type":"talk","link":"https:\/\/simon.blog\/de\/talk\/greener-better-faster-stronger\/","title":{"rendered":"Greener, Better, Faster, Stronger"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jede Website verursacht CO2 Emissionen, wenn sie aufgerufen wird. Wie hoch die Emissionen sind, h\u00e4ngt von verschiedenen Faktoren ab. Egal ob wir eine Website selbst gebaut haben, oder nur betreuen. Ob sie mit einem Pagebuilder, dem Classic Editor oder einem Block Theme gebaut wurde. In den meisten F\u00e4llen gibt es m\u00f6gliche Anpassungen, die den CO2-Aussto\u00df reduzieren und WordPress ganz nebenbei auch stabiler, zuverl\u00e4ssiger und leistungsf\u00e4higer machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Workshop besch\u00e4ftigen wir uns sowohl mit solchen Ma\u00dfnahmen, die von Einsteigern ohne tiefere Code-Kenntnisse durchgef\u00fchrt werden k\u00f6nnen, als auch mit aufw\u00e4ndigeren Anpassungen an Hosting, Themes und Konfiguration einer WordPress-Installation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jede Website verursacht CO2 Emissionen, wenn sie aufgerufen wird. Wie hoch die Emissionen sind, h\u00e4ngt von verschiedenen Faktoren ab. Egal ob wir eine Website selbst gebaut haben, oder nur betreuen. Ob sie mit einem Pagebuilder, dem Classic Editor oder einem Block Theme gebaut wurde. In den meisten F\u00e4llen gibt es m\u00f6gliche Anpassungen, die den CO2-Aussto\u00df reduzieren und WordPress ganz nebenbei auch stabiler, zuverl\u00e4ssiger und leistungsf\u00e4higer machen.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_talk_slides_url":"","_talk_recording_url":"","_talk_event_name":"","_talk_duration":"20 min","_talk_cover_emoji":"\ud83e\udeb4","_talk_target_audience":"Einsteiger, Fortgeschrittene","_talk_format":"Workshop \/ Talk","_talk_event_url":"","_talk_status":"available","_talk_occurrences":"[{\"date\":\"2024-04-20\",\"event_name\":\"WordCamp Leipzig\",\"location\":\"Leipzig\",\"event_url\":\"\",\"slides_url\":\"\",\"recording_url\":\"https:\\\/\\\/wordpress.tv\\\/2024\\\/04\\\/21\\\/greener-better-faster-stronger-wie-websites-umweltfreundlicher-und-zuverlaessiger-werden\\\/\",\"language\":\"de_DE\"},{\"date\":\"2024-11-30\",\"event_name\":\"WordCamp Netherland\",\"location\":\"Den Haag\",\"event_url\":\"\",\"slides_url\":\"\",\"recording_url\":\"\",\"language\":\"en_US\"},{\"date\":\"2024-04-05\",\"event_name\":\"WordCamp Vienna\",\"location\":\"Wien\",\"event_url\":\"https:\\\/\\\/vienna.wordcamp.org\\\/2024\\\/session\\\/greener-better-faster-stronger-wie-websites-umweltfreundlicher-und-zuverlassiger-werden\\\/\",\"slides_url\":\"\",\"recording_url\":\"\",\"language\":\"de_DE\"},{\"date\":\"2024-10-09\",\"event_name\":\"WP Meetup Bonn\",\"location\":\"Bonn\",\"event_url\":\"https:\\\/\\\/www.meetup.com\\\/wordpress-meetup-bonn-wpbn\\\/events\\\/303763031\\\/\",\"slides_url\":\"\",\"recording_url\":\"\",\"language\":\"de_DE\"},{\"date\":\"2024-04-24\",\"event_name\":\"WP Meetup Hamburg\",\"location\":\"Hamburg\",\"event_url\":\"https:\\\/\\\/www.wpmeetup-hamburg.de\\\/wordpress-meetup-115-mai-2024-nachhaltige-websites\\\/\",\"slides_url\":\"\",\"recording_url\":\"\",\"language\":\"de_DE\"}]","footnotes":"","_image_socialiser_subtitle":"","_image_socialiser_title":"","_image_socialiser_override_id":0,"_image_socialiser_template_id":""},"talk-topics":[],"class_list":["post-1003","talk","type-talk","status-publish","hentry"],"talk_status":"available","occurrences":[{"date":"2024-04-05","event_name":"WordCamp Vienna","location":"Wien","event_url":"https:\/\/vienna.wordcamp.org\/2024\/session\/greener-better-faster-stronger-wie-websites-umweltfreundlicher-und-zuverlassiger-werden\/","slides_url":"","recording_url":"","language":"de_DE","url":"https:\/\/simon.blog\/de\/talk\/greener-better-faster-stronger\/20240405","language_name":"Deutsch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/de.png"},{"date":"2024-04-20","event_name":"WordCamp Leipzig","location":"Leipzig","event_url":"","slides_url":"","recording_url":"https:\/\/wordpress.tv\/2024\/04\/21\/greener-better-faster-stronger-wie-websites-umweltfreundlicher-und-zuverlaessiger-werden\/","language":"de_DE","url":"https:\/\/simon.blog\/de\/talk\/greener-better-faster-stronger\/20240420","language_name":"Deutsch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/de.png"},{"date":"2024-04-24","event_name":"WP Meetup Hamburg","location":"Hamburg","event_url":"https:\/\/www.wpmeetup-hamburg.de\/wordpress-meetup-115-mai-2024-nachhaltige-websites\/","slides_url":"","recording_url":"","language":"de_DE","url":"https:\/\/simon.blog\/de\/talk\/greener-better-faster-stronger\/20240424","language_name":"Deutsch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/de.png"},{"date":"2024-10-09","event_name":"WP Meetup Bonn","location":"Bonn","event_url":"https:\/\/www.meetup.com\/wordpress-meetup-bonn-wpbn\/events\/303763031\/","slides_url":"","recording_url":"","language":"de_DE","url":"https:\/\/simon.blog\/de\/talk\/greener-better-faster-stronger\/20241009","language_name":"Deutsch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/de.png"},{"date":"2024-11-30","event_name":"WordCamp Netherland","location":"Den Haag","event_url":"","slides_url":"","recording_url":"","language":"en_US","url":"https:\/\/simon.blog\/de\/talk\/greener-better-faster-stronger\/20241130","language_name":"Englisch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/us.png"}],"talk_languages":["de_DE","en_US"],"_links":{"self":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/1003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks"}],"about":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/types\/talk"}],"version-history":[{"count":2,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/1003\/revisions"}],"predecessor-version":[{"id":6405,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/1003\/revisions\/6405"}],"wp:attachment":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/media?parent=1003"}],"wp:term":[{"taxonomy":"talk_topic","embeddable":true,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talk-topics?post=1003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}