{"id":6368,"date":"2018-11-07T17:06:00","date_gmt":"2018-11-07T16:06:00","guid":{"rendered":"https:\/\/simon.blog\/de\/?post_type=talk&#038;p=6368"},"modified":"2026-06-10T10:49:38","modified_gmt":"2026-06-10T08:49:38","slug":"amp-like-dynamite","status":"publish","type":"talk","link":"https:\/\/simon.blog\/de\/talk\/amp-like-dynamite\/","title":{"rendered":"AMP \u2013 Like Dynamite"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">W\u00e4hrend Websites von Jahr zu Jahr gr\u00f6\u00dfer und langsamer werden, versucht Google mit AMP eine eingedampfte Version von HTML zu forcieren. Was sich nach einem Eingriff des Suchmaschinen-Giganten in unser Open-Source-\u00d6kosystem anf\u00fchlt, k\u00f6nnte sich als gro\u00dfe Hilfe f\u00fcr das freie Web erweisen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Kontext von WordPress als Content-Management-System stellen sich dann nat\u00fcrlich auch noch die Frage, wie AMP und WordPress miteinander verheiratet werden k\u00f6nnen. Au\u00dferdem werfen wir einen Blick auf die technischen Implikationen von AMP, Unterschiede und Gemeinsamkeiten zu HTML und m\u00f6gliche Alternativen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend Websites von Jahr zu Jahr gr\u00f6\u00dfer und langsamer werden, versucht Google mit AMP eine eingedampfte Version von HTML zu forcieren. Was sich nach einem Eingriff des Suchmaschinen-Giganten in unser Open-Source-\u00d6kosystem anf\u00fchlt, k\u00f6nnte sich als&hellip;<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_talk_slides_url":"https:\/\/speakerdeck.com\/krafit\/amp-like-dynamite","_talk_recording_url":"","_talk_event_name":"","_talk_duration":"20 min + Diskussion","_talk_cover_emoji":"\ud83e\udde8","_talk_target_audience":"","_talk_format":"","_talk_event_url":"","_talk_status":"retired","_talk_occurrences":"[{\"date\":\"2018-11-07\",\"event_name\":\"WP Meetup Stuttgart\",\"location\":\"Stuttgart\",\"event_url\":\"\",\"slides_url\":\"\",\"recording_url\":\"\",\"language\":\"de_DE\"},{\"date\":\"2018-11-06\",\"event_name\":\"WP Meetup Aachen\",\"location\":\"Aachen\",\"event_url\":\"https:\\\/\\\/www.meetup.com\\\/aachen-wordpress-meetup\\\/events\\\/255490053\\\/\",\"slides_url\":\"\",\"recording_url\":\"\",\"language\":\"de_DE\"}]","footnotes":"","_image_socialiser_subtitle":"","_image_socialiser_title":"","_image_socialiser_override_id":0,"_image_socialiser_template_id":""},"talk-topics":[],"class_list":["post-6368","talk","type-talk","status-publish","hentry"],"talk_status":"retired","occurrences":[{"date":"2018-11-06","event_name":"WP Meetup Aachen","location":"Aachen","event_url":"https:\/\/www.meetup.com\/aachen-wordpress-meetup\/events\/255490053\/","slides_url":"","recording_url":"","language":"de_DE","url":"https:\/\/simon.blog\/de\/talk\/amp-like-dynamite\/20181106","language_name":"Deutsch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/de.png"},{"date":"2018-11-07","event_name":"WP Meetup Stuttgart","location":"Stuttgart","event_url":"","slides_url":"","recording_url":"","language":"de_DE","url":"https:\/\/simon.blog\/de\/talk\/amp-like-dynamite\/20181107","language_name":"Deutsch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/de.png"}],"talk_languages":["de_DE"],"_links":{"self":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/6368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks"}],"about":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/types\/talk"}],"version-history":[{"count":1,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/6368\/revisions"}],"predecessor-version":[{"id":6369,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/6368\/revisions\/6369"}],"wp:attachment":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/media?parent=6368"}],"wp:term":[{"taxonomy":"talk_topic","embeddable":true,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talk-topics?post=6368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}