{"id":6383,"date":"2023-10-10T12:00:00","date_gmt":"2023-10-10T10:00:00","guid":{"rendered":"https:\/\/simon.blog\/?post_type=talk&#038;p=1005"},"modified":"2026-06-16T15:15:49","modified_gmt":"2026-06-16T13:15:49","slug":"wordpress-login-security","status":"publish","type":"talk","link":"https:\/\/simon.blog\/de\/talk\/wordpress-login-security\/","title":{"rendered":"WordPress Login-Security"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der Login-Bereich von WordPress ist aus Sicht der Sicherheit fast zwangsl\u00e4ufig eine Schwachstelle. Alles und Jede*r mit einer groben Vorstellung von Benutzername und\/oder Passwort stehen von hier aus die innersten Geheimnisse einer Installation offen. Mit Admin-Rechten ausgestattet, k\u00f6nnen grundlegende \u00c4nderungen an Plugins, Aussehen und Inhalt einer Website vorgenommen werden. Dieser Vortrag besch\u00e4ftigt sich mit einigen einfachen und effektiven Gegenma\u00dfnahmen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Login-Bereich von WordPress ist aus Sicht der Sicherheit fast zwangsl\u00e4ufig eine Schwachstelle. Alles und Jede*r mit einer groben Vorstellung von Benutzername und\/oder Passwort stehen von hier aus die innersten Geheimnisse einer Installation offen. Mit Admin-Rechten ausgestattet, k\u00f6nnen grundlegende \u00c4nderungen an Plugins, Aussehen und Inhalt einer Website vorgenommen werden. Dieser Vortrag besch\u00e4ftigt sich mit einigen einfachen und effektiven Gegenma\u00dfnahmen.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_talk_slides_url":"","_talk_recording_url":"https:\/\/wordpress.tv\/2023\/10\/21\/angelo-cali-simon-kraft-wordpress-login-security\/","_talk_event_name":"","_talk_duration":"30 min","_talk_cover_emoji":"\ud83d\udd12","_talk_target_audience":"Einsteiger, Fortgeschrittene","_talk_format":"","_talk_event_url":"","_talk_status":"available","_talk_occurrences":"[{\"date\":\"2023-10-21\",\"event_name\":\"WordCamp Germany\",\"location\":\"Gerolstein\",\"event_url\":\"https:\\\/\\\/germany.wordcamp.org\\\/2023\\\/session\\\/wordpress-login-security\\\/\",\"slides_url\":\"\",\"recording_url\":\"https:\\\/\\\/wordpress.tv\\\/2023\\\/10\\\/21\\\/angelo-cali-simon-kraft-wordpress-login-security\\\/\",\"language\":\"de_DE\"},{\"date\":\"2024-03-11\",\"event_name\":\"WP Meetup Konstanz\",\"location\":\"Konstanz\",\"event_url\":\"https:\\\/\\\/www.meetup.com\\\/konstanz-wordpress\\\/events\\\/298501761\\\/\",\"slides_url\":\"\",\"recording_url\":\"\",\"language\":\"de_DE\"}]","footnotes":"","_image_socialiser_subtitle":"","_image_socialiser_title":"","_image_socialiser_override_id":0,"_image_socialiser_template_id":""},"talk-topics":[],"class_list":["post-6383","talk","type-talk","status-publish","hentry"],"talk_status":"available","occurrences":[{"date":"2023-10-21","event_name":"WordCamp Germany","location":"Gerolstein","event_url":"https:\/\/germany.wordcamp.org\/2023\/session\/wordpress-login-security\/","slides_url":"","recording_url":"https:\/\/wordpress.tv\/2023\/10\/21\/angelo-cali-simon-kraft-wordpress-login-security\/","language":"de_DE","url":"https:\/\/simon.blog\/de\/talk\/wordpress-login-security\/20231021","language_name":"Deutsch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/de.png"},{"date":"2024-03-11","event_name":"WP Meetup Konstanz","location":"Konstanz","event_url":"https:\/\/www.meetup.com\/konstanz-wordpress\/events\/298501761\/","slides_url":"","recording_url":"","language":"de_DE","url":"https:\/\/simon.blog\/de\/talk\/wordpress-login-security\/20240311","language_name":"Deutsch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/de.png"}],"talk_languages":["de_DE"],"_links":{"self":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/6383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks"}],"about":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/types\/talk"}],"version-history":[{"count":1,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/6383\/revisions"}],"predecessor-version":[{"id":6415,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/6383\/revisions\/6415"}],"wp:attachment":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/media?parent=6383"}],"wp:term":[{"taxonomy":"talk_topic","embeddable":true,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talk-topics?post=6383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}