{"id":6505,"date":"2025-01-05T13:58:00","date_gmt":"2025-01-05T12:58:00","guid":{"rendered":"https:\/\/simon.blog\/de\/?post_type=talk&#038;p=6505"},"modified":"2026-06-10T14:12:18","modified_gmt":"2026-06-10T12:12:18","slug":"newsletter-mit-wordpress","status":"publish","type":"talk","link":"https:\/\/simon.blog\/de\/talk\/newsletter-mit-wordpress\/","title":{"rendered":"Newsletter schreiben mit WordPress"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Auch wenn sie anachronistisch erscheinen, sind Newsletter auch dieser Tage noch eine tolle M\u00f6glichkeit, Informationen zu verbreiten, ohne dabei von gro\u00dfen Plattformen abh\u00e4ngig zu sein. WordPress kann hier ein n\u00fctzliches Werkzeug sein.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch wenn sie anachronistisch erscheinen, sind Newsletter auch dieser Tage noch eine tolle M\u00f6glichkeit, Informationen zu verbreiten, ohne dabei von gro\u00dfen Plattformen abh\u00e4ngig zu sein. WordPress kann hier ein n\u00fctzliches Werkzeug sein.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_talk_slides_url":"","_talk_recording_url":"","_talk_event_name":"","_talk_duration":"30 min","_talk_cover_emoji":"\ud83d\udc8c","_talk_target_audience":"Einsteiger*innen, Fortgeschrittene","_talk_format":"Vortrag","_talk_event_url":"","_talk_status":"retired","_talk_occurrences":"[{\"date\":\"2025-02-11\",\"event_name\":\"WP Meetup Jena\",\"location\":\"Jena\",\"event_url\":\"https:\\\/\\\/www.meetup.com\\\/jena-wordpress-meetup\\\/events\\\/300546992\\\/\",\"slides_url\":\"\",\"recording_url\":\"\",\"language\":\"de_DE\"}]","footnotes":"","_image_socialiser_subtitle":"","_image_socialiser_title":"","_image_socialiser_override_id":0,"_image_socialiser_template_id":""},"talk-topics":[],"class_list":["post-6505","talk","type-talk","status-publish","hentry"],"talk_status":"retired","occurrences":[{"date":"2025-02-11","event_name":"WP Meetup Jena","location":"Jena","event_url":"https:\/\/www.meetup.com\/jena-wordpress-meetup\/events\/300546992\/","slides_url":"","recording_url":"","language":"de_DE","url":"https:\/\/simon.blog\/de\/talk\/newsletter-mit-wordpress\/20250211","language_name":"Deutsch","language_flag_url":"https:\/\/simon.blog\/de\/wp-content\/plugins\/multisite-language-switcher\/assets\/flags\/de.png"}],"talk_languages":["de_DE"],"_links":{"self":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/6505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks"}],"about":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/types\/talk"}],"version-history":[{"count":1,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/6505\/revisions"}],"predecessor-version":[{"id":6506,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talks\/6505\/revisions\/6506"}],"wp:attachment":[{"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/media?parent=6505"}],"wp:term":[{"taxonomy":"talk_topic","embeddable":true,"href":"https:\/\/simon.blog\/de\/wp-json\/wp\/v2\/talk-topics?post=6505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}